{"id":3290,"date":"2022-10-22T00:24:26","date_gmt":"2022-10-22T00:24:26","guid":{"rendered":"https:\/\/www.oncoalicia.com\/uncategorized-ca\/apple-pudding\/"},"modified":"2023-08-14T19:24:07","modified_gmt":"2023-08-14T19:24:07","slug":"apple-pudding","status":"publish","type":"post","link":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/","title":{"rendered":"Apple pudding"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Pudin de manzana\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/h8D6VAusT1g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178,94,79,80,170,81,154,148,172,158,86,106,87,77,101,91,99,100,104,150,107,93,98,156,103,105,160],"tags":[],"class_list":["post-3290","post","type-post","status-publish","format-standard","hentry","category-breakfasts-lunches-snacks-and-desserts","category-breast","category-colon","category-colostomies","category-dairy","category-diarrhea","category-difficulty-swallowing","category-dry-mouth","category-eggs","category-esophagitis","category-flatulence","category-fluid-retention","category-fruits","category-head-and-neck","category-heartburn-or-heartburn","category-hypertension","category-loss-of-appetite","category-loss-of-muscle-mass","category-lung","category-mucositis-en","category-no-dried-fruit","category-normally-functioning-ileostomy","category-osteoporosis-en","category-painful-swallowing","category-prostate","category-recipes","category-severe-mucositis","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apple pudding - Oncoalicia<\/title>\n<meta name=\"description\" content=\"Discover how to cook Apple pudding, ideal for people undergoing cancer treatment.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apple pudding - Oncoalicia\" \/>\n<meta property=\"og:description\" content=\"Discover how to cook Apple pudding, ideal for people undergoing cancer treatment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/\" \/>\n<meta property=\"og:site_name\" content=\"Oncoalicia\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-22T00:24:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-14T19:24:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Puding-de-poma.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fcatalunyalapedrera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fcatalunyalapedrera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/\"},\"author\":{\"name\":\"fcatalunyalapedrera\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#\\\/schema\\\/person\\\/58c47a4b9d85f351564760b900081128\"},\"headline\":\"Apple pudding\",\"datePublished\":\"2022-10-22T00:24:26+00:00\",\"dateModified\":\"2023-08-14T19:24:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#organization\"},\"articleSection\":[\"Breakfasts, lunches, snacks and desserts\",\"Breast\",\"Colon\",\"Colostomies\",\"Dairy\",\"Diarrhea\",\"Difficulty swallowing\",\"Dry mouth\",\"Eggs\",\"Esophagitis\",\"Flatulence\",\"Fluid retention\",\"Fruits\",\"Head and neck\",\"Heartburn or heartburn\",\"Hypertension\",\"Loss of appetite\",\"Loss of muscle mass\",\"Lung\",\"Mucositis\",\"No dried fruit\",\"Normally functioning ileostomy\",\"Osteoporosis\",\"Painful swallowing\",\"Prostate\",\"Recipes\",\"Severe mucositis\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/\",\"name\":\"Apple pudding - Oncoalicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#website\"},\"datePublished\":\"2022-10-22T00:24:26+00:00\",\"dateModified\":\"2023-08-14T19:24:07+00:00\",\"description\":\"Discover how to cook Apple pudding, ideal for people undergoing cancer treatment.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/recipes\\\/apple-pudding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apple pudding\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/\",\"name\":\"Oncoal\u00edcia\",\"description\":\"Comer durante el Tratamiento del C\u00e1ncer\",\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#organization\"},\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#organization\",\"name\":\"Oncoal\u00edcia\",\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"width\":300,\"height\":300,\"caption\":\"Oncoal\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/#\\\/schema\\\/person\\\/58c47a4b9d85f351564760b900081128\",\"name\":\"fcatalunyalapedrera\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/en\\\/author\\\/fcatalunyalapedrera\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apple pudding - Oncoalicia","description":"Discover how to cook Apple pudding, ideal for people undergoing cancer treatment.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/","og_locale":"en_US","og_type":"article","og_title":"Apple pudding - Oncoalicia","og_description":"Discover how to cook Apple pudding, ideal for people undergoing cancer treatment.","og_url":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/","og_site_name":"Oncoalicia","article_published_time":"2022-10-22T00:24:26+00:00","article_modified_time":"2023-08-14T19:24:07+00:00","og_image":[{"width":1000,"height":1333,"url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Puding-de-poma.jpg","type":"image\/jpeg"}],"author":"fcatalunyalapedrera","twitter_card":"summary_large_image","twitter_misc":{"Written by":"fcatalunyalapedrera","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/#article","isPartOf":{"@id":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/"},"author":{"name":"fcatalunyalapedrera","@id":"https:\/\/oncoalicia.com\/en\/#\/schema\/person\/58c47a4b9d85f351564760b900081128"},"headline":"Apple pudding","datePublished":"2022-10-22T00:24:26+00:00","dateModified":"2023-08-14T19:24:07+00:00","mainEntityOfPage":{"@id":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/"},"wordCount":12,"publisher":{"@id":"https:\/\/oncoalicia.com\/en\/#organization"},"articleSection":["Breakfasts, lunches, snacks and desserts","Breast","Colon","Colostomies","Dairy","Diarrhea","Difficulty swallowing","Dry mouth","Eggs","Esophagitis","Flatulence","Fluid retention","Fruits","Head and neck","Heartburn or heartburn","Hypertension","Loss of appetite","Loss of muscle mass","Lung","Mucositis","No dried fruit","Normally functioning ileostomy","Osteoporosis","Painful swallowing","Prostate","Recipes","Severe mucositis"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/","url":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/","name":"Apple pudding - Oncoalicia","isPartOf":{"@id":"https:\/\/oncoalicia.com\/en\/#website"},"datePublished":"2022-10-22T00:24:26+00:00","dateModified":"2023-08-14T19:24:07+00:00","description":"Discover how to cook Apple pudding, ideal for people undergoing cancer treatment.","breadcrumb":{"@id":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oncoalicia.com\/en\/recipes\/apple-pudding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oncoalicia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Apple pudding"}]},{"@type":"WebSite","@id":"https:\/\/oncoalicia.com\/en\/#website","url":"https:\/\/oncoalicia.com\/en\/","name":"Oncoal\u00edcia","description":"Comer durante el Tratamiento del C\u00e1ncer","publisher":{"@id":"https:\/\/oncoalicia.com\/en\/#organization"},"alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oncoalicia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/oncoalicia.com\/en\/#organization","name":"Oncoal\u00edcia","alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","url":"https:\/\/oncoalicia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oncoalicia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","width":300,"height":300,"caption":"Oncoal\u00edcia"},"image":{"@id":"https:\/\/oncoalicia.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oncoalicia.com\/en\/#\/schema\/person\/58c47a4b9d85f351564760b900081128","name":"fcatalunyalapedrera","url":"https:\/\/oncoalicia.com\/en\/author\/fcatalunyalapedrera\/"}]}},"_links":{"self":[{"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/posts\/3290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/comments?post=3290"}],"version-history":[{"count":0,"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/posts\/3290\/revisions"}],"wp:attachment":[{"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/media?parent=3290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/categories?post=3290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oncoalicia.com\/en\/wp-json\/wp\/v2\/tags?post=3290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}