{"id":3907,"date":"2022-05-14T08:31:26","date_gmt":"2022-05-14T06:31:26","guid":{"rendered":"https:\/\/www.oncoalicia.com\/alimentacion-durante-el-tratamiento-del-cancer-de-pulmon\/dolor-en-la-deglucion\/"},"modified":"2026-06-28T12:22:39","modified_gmt":"2026-06-28T10:22:39","slug":"dolor-en-la-deglucion","status":"publish","type":"page","link":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/","title":{"rendered":"Recomendaciones diet\u00e9tico-culinarias para el dolor en la degluci\u00f3n en el c\u00e1ncer de pulm\u00f3n"},"content":{"rendered":"<div class=\"row\">\n      <!-- BAJADA --><\/p>\n<div class=\"col-md-12 subtitle-mitos\">\n<p>La esofagitis se define como la inflamaci\u00f3n del es\u00f3fago, que provoca dolor al ingerir los alimentos. Aparece dada la cercan\u00eda del es\u00f3fago al pulm\u00f3n, especialmente durante el tratamiento con radioterapia. Normalmente se da de forma progresiva y perdura hasta pocas semanas despu\u00e9s de finalizar el tratamiento. En funci\u00f3n del dolor que aparezca con la ingesta diferenciamos entre esofagitis leve y esofagitis grave, por lo que se deber\u00e1 adaptar la textura de los alimentos seg\u00fan cada situaci\u00f3n. En cualquier caso, se deber\u00e1 siempre notificar al personal m\u00e9dico de referencia la aparici\u00f3n de dolor al deglutir para valorar la toma de medicaci\u00f3n para controlar el dolor.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row p-40 w-60\">\n<div class=\"col-md-12 text-center\">\n<h2 class=\"h3 recomanem-efectes-cancer\">\u00bfQU\u00c9 TE RECOMENDAMOS?<\/h2>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-1\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Mantener una buena hidrataci\u00f3n. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n          <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-1\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Se recomienda beber alrededor de dos litros diarios de agua, infusiones, zumos de frutas no \u00e1cidas, caldos, gelatinas<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Evitar alimentos que puedan irritar la mucosa del es\u00f3fago. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Bebidas alcoh\u00f3licas, caf\u00e9, bebidas con gas y otros refrescos \u00e1cidos o irritantes (bebidas de cola).<\/li>\n<li>Alimentos \u00e1cidos (tomate, pimiento crudo, kiwi, lim\u00f3n, naranja, fresa, mandarina, mango, pi\u00f1a, vinagre, encurtidos\u2026).<\/li>\n<li>Alimentos muy condimentados, picantes o salados.<\/li>\n<li>Alimentos secos o de consistencia dura (pan con corteza, pan tostado, biscotes, palitos, frutos secos, galletas secas, chips, quesos secos o muy curados, y cocciones tipo rebozado o gratinado).<\/li>\n<li>Alimentos pegajosos (como el pur\u00e9 de patata, las croquetas, el pl\u00e1tano, el chocolate\u2026).<\/li>\n<li>Alimentos fibrosos, como algunas carnes a la plancha, alcachofas y esp\u00e1rragos.<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-2\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Comer poco y a menudo. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n          <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-2\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Escoger elaboraciones y alimentos de peque\u00f1os vol\u00famenes con alto valor nutritivo. Intentar mantener la ingesta y recordar la importancia de asegurar una alimentaci\u00f3n completa.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-3\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Adaptar la textura de los alimentos seg\u00fan la intensidad de la esofagitis. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-3\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Cuando esta sea leve:\n<ul>\n                              <\/ul>\n<ol>Comer preferiblemente alimentos de textura blanda (guisos, sopas, cremas, flanes, quesos tiernos, frutas maduras y dulces, pastas y arroces sobrecocinados, pescado y carnes muy tiernos).<\/ol>\n<ol>Cocer los alimentos hasta que queden blandos y acompa\u00f1arlos con salsas, caldos o zumos, especialmente aquellos m\u00e1s secos. Preparar las carnes y vegetales en olla a presi\u00f3n ayudar\u00e1 a conseguir texturas m\u00e1s tiernas y suaves.<\/ol>\n<ol>Cortar los ingredientes en trozos muy peque\u00f1os y masticar lentamente.<\/ol>\n<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algunas recetas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <a href=\"https:\/\/oncoalicia.com\/es\/recetas\/pastel-de-pavo-y-verduras\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                    <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Pastel-de-pavo-y-verduras.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Pastel de pavo y verduras\n                                    <\/div>\n<\/p><\/div>\n<p>                            <\/a>\n                        <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <a href=\"https:\/\/oncoalicia.com\/es\/recetas\/minisandwiches-de-aguacate\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                    <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Mini-sandvitxos-4.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Minisandwiches de aguacate\n                                    <\/div>\n<\/p><\/div>\n<p>                            <\/a>\n                        <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <a href=\"https:\/\/oncoalicia.com\/es\/recetas\/patatas-rellenas-en-el-microondas\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                    <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Patatas-al-microondas-rellenas-al-gusto.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Patatas rellenas en el microondas\n                                    <\/div>\n<\/p><\/div>\n<p>                            <\/a>\n                        <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Cuando esta sea grave, se deber\u00e1 modificar la textura de la mayor\u00eda de los alimentos y preparaciones s\u00f3lidas, tritur\u00e1ndolos.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 descrip\">\n<table class=\"table\">\n<tr>\n<td class=\"table-title\">\u00bfC\u00f3mo adaptar la alimentaci\u00f3n a una textura triturada?<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">\nComer triturado no significa renunciar al placer de comer o a los sabores t\u00edpicos de nuestra alimentaci\u00f3n habitual. Casi todas las elaboraciones y platos de una alimentaci\u00f3n est\u00e1ndar se pueden adaptar a una textura triturada. Por lo tanto, no hay que preparar siempre elaboraciones concretas o espec\u00edficas para la persona que debe comer triturado. Los platos t\u00edpicos y m\u00e1s comunes de nuestra alimentaci\u00f3n, como la ensalada, el pollo a la plancha, la tortilla de patatas, la paella o los espaguetis con tomate, se pueden adaptar sin mucha dificultad, y as\u00ed se permite que toda la familia siga comiendo lo mismo y solo cambie la textura.\n                          <\/td>\n<\/tr>\n<tr>\n<td align=\"left\">\nCasi cualquier plato se puede adaptar a una textura triturada. Para ello, hay que tener en cuenta los siguientes aspectos:<\/p>\n<ul>\n<li>Conocer de qu\u00e9 tipo de plato se trata:\n<ul>\n                                  <\/ul>\n<ol>Asegurarse de que ha sido conservado correctamente y que est\u00e1 en perfecto estado para ser consumido.<\/ol>\n<ol>Asegurarse de que no contenga elementos s\u00f3lidos que puedan dificultar el triturado.<\/ol>\n<\/li>\n<\/ul>\n<li>Visualizar c\u00f3mo se puede hacer mejor la adaptaci\u00f3n (si contiene elementos que den consistencia, si tiene l\u00edquido para triturar o no, de qu\u00e9 forma se quiere triturar, etc.).<\/li>\n<li>Recordar que en general es mejor calentar el plato para poder triturarlo m\u00e1s f\u00e1cilmente.<\/li>\n<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">\nRecordar que las prote\u00ednas son imprescindibles durante el tratamiento de un c\u00e1ncer, por lo tanto, a pesar de comer triturado es preciso asegurarse de que los pur\u00e9s incluyen carne, pescado o huevos o fuentes proteicas vegetales, tanto en el almuerzo como en la cena.<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">\n Cuando se come triturado puede existir m\u00e1s dificultad para acabarse el plato, ya que la textura y el color homog\u00e9neos pueden aburrir. Por lo tanto, es importante intentar mezclar diferentes texturas o consistencias y colores, y evitar vol\u00famenes muy grandes. Se recomienda hacer un triturado \u00fanico, de unos 300 ml como m\u00e1ximo (un bol mediano), o dos triturados peque\u00f1os, repartiendo el volumen, simulando un primer y un segundo plato.\n                          <\/td>\n<\/tr>\n<\/table><\/div>\n<div class=\"col-md-12 descrip\">\n<table class=\"table\">\n<tr>\n<td colspan=\"3\" class=\"table-title\">Tabla para aprender a adaptar platos habituales a texturas trituradas<\/td>\n<\/tr>\n<tr>\n<td><strong>Elaboraci\u00f3n base<\/strong><\/td>\n<td align=\"left\">\n                            <strong>Ingredientes necesarios para adaptarla<\/strong>\n                          <\/td>\n<td align=\"left\">\n                            <strong>Procedimiento para realizar un triturado<\/strong>\n                          <\/td>\n<\/tr>\n<tr>\n<td>Escudella y carne de olla<\/td>\n<td align=\"left\">\n Ninguno\n                          <\/td>\n<td align=\"left\">\n<ul style=\"padding-left: 0px;\">\n<li>Deshuese la carne y desmenuce.<\/li>\n<li>Repartir la verdura del cocido: juntar una parte con la carne y la patata, y la otra con la pasta hervida.<\/li>\n<li>Triture la carne con la verdura y la patata y a\u00f1ade el caldo suficiente para hacer un triturado \u00f3ptimo.<\/li>\n<li>Triture la pasta con la verdura que queda y a\u00f1ade el caldo necesario.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Tortilla de patatas y cebolla<\/td>\n<td align=\"left\">\n Caldo o leche\n                          <\/td>\n<td align=\"left\">\n<ul style=\"padding-left: 0px;\">\n<li>Triture todo con el caldo o leche suficientes para hacer un triturado \u00f3ptimo.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Lasa\u00f1a de pollo<\/td>\n<td align=\"left\">\n Caldo de pollo o leche\n                          <\/td>\n<td align=\"left\">\n<ul style=\"padding-left: 0px;\">\n<li>Triture todo con el caldo o leche suficientes para hacer un triturado \u00f3ptimo.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algunas recetas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <a href=\"https:\/\/oncoalicia.com\/es\/recetas\/risotto-de-verduras-y-bacalao-textura-modificada\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                    <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Risotto-de-verdures-y-bacalao-tex-mod.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n &#8216;Risotto&#8217; de verduras y bacalao (textura modificada)\n                                    <\/div>\n<\/p><\/div>\n<p>                            <\/a>\n                        <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <a href=\"https:\/\/oncoalicia.com\/es\/recetas\/ensalada-de-tres-cereales-con-salmon-textura-modificada\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                    <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Empedrat-de-tres-cereals-triturada-scaled-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Ensalada de tres cereales con salm\u00f3n (textura modificada)\n                                    <\/div>\n<\/p><\/div>\n<p>                            <\/a>\n                        <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <a href=\"https:\/\/oncoalicia.com\/es\/recetas\/dahl-hindu-textura-modificada\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                    <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Dahl-hindu-triturado-scaled-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Dahl hind\u00fa (textura modificada)\n                                    <\/div>\n<\/p><\/div>\n<p>                            <\/a>\n                        <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-4\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Ejemplo de men\u00fa de textura blanda de f\u00e1cil degluci\u00f3n. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n          <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-4\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<table class=\"table\">\n<tr>\n<td><\/td>\n<td style=\"text-align:center;\"><b>D\u00eda 1<\/b><\/td>\n<td style=\"text-align:center;\"><b>D\u00eda 2<\/b><\/td>\n<td style=\"text-align:center;\"><b>D\u00eda 3<\/b><\/td>\n<\/tr>\n<tr>\n<td>Desayuno<\/td>\n<td align=\"left\">\n<ul>\n<li>Pan de molde sin corteza con tomate rallado y rodajas de aguacate.<\/li>\n<li>Triturado de una fruta de temporada.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/batido-de-platano-y-avellanas\/\" target=\"_blank\" rel=\"noopener\">Batido de pl\u00e1tano y avellanas.<\/a><\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li>Triturado de galletas con leche.<\/li>\n<li>Pl\u00e1tano aplastado.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Almuerzo<\/td>\n<td align=\"left\">\n<ul>\n<li>Plato \u00fanico: lentejas estofadas.<\/li>\n<li>Flan.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/risotto-de-verduras-y-bacalao-textura-modificada\/\" target=\"_blank\" rel=\"noopener\">Plato \u00fanico: risotto de verduras y bacalao.<\/a><\/li>\n<li>Batido de fruta de temporada.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li>Crema de setas.<\/li>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/pastel-de-pavo-y-verduras\/\" target=\"_blank\" rel=\"noopener\">Tarta de pavo y verduras.<\/a><\/li>\n<li>Pera cocida con yogur.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Cena<\/td>\n<td align=\"left\">\n<ul>\n<li>Crema de calabac\u00edn.<\/li>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/papillote-de-pescado-blanco-con-salsa-verde\/\" target=\"_blank\" rel=\"noopener\">Papillota de pescado blanco con salsa verde.<\/a><\/li>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/manzana-al-microondas-con-canela\/\" target=\"_blank\" rel=\"noopener\">Manzana en el microondas con canela.<\/a><\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li>Quema de Calabaza.<\/li>\n<li>Yogur natural.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li>Jud\u00eda tierna y patatas aplastadas.<\/li>\n<li>Pescado azul a la plancha con salsa de lim\u00f3n.<\/li>\n<li>Macedonia de frutas maduras.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-5\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Ejemplo de men\u00fa de textura pur\u00e9. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n          <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-5\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<table class=\"table\">\n<tr>\n<td><\/td>\n<td style=\"text-align:center;\"><b>D\u00eda 1<\/b><\/td>\n<td style=\"text-align:center;\"><b>D\u00eda 2<\/b><\/td>\n<td style=\"text-align:center;\"><b>D\u00eda 3<\/b><\/td>\n<\/tr>\n<tr>\n<td>Desayuno<\/td>\n<td align=\"left\">\n<ul>\n<li>Triturado de cereales integrales con leche.<\/li>\n<li>Triturado de una fruta de temporada.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/batido-de-platano-y-avellanas\/\" target=\"_blank\" rel=\"noopener\">Batido de pl\u00e1tano y avellanas.<\/a><\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li>Triturado de galletas con leche.<\/li>\n<li>Triturado de una fruta de temporada.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Almuerzo<\/td>\n<td align=\"left\">\n<ul>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/lentejas-estofadas-con-jamon-textura-modificada\/\" target=\"_blank\" rel=\"noopener\">Plato \u00fanico: triturado de lentejas estofadas con jam\u00f3n.<\/a><\/li>\n<li>Flan.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li>Crema de setas.<\/li>\n<li>Triturado de cerdo marinado con pi\u00f1a.<\/li>\n<li>Triturado de fruta de temporada.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/risotto-de-verduras-y-bacalao-textura-modificada\/\" target=\"_blank\" rel=\"noopener\">Plato \u00fanico: risotto de verduras y bacalao triturado.<\/a><\/li>\n<li>Triturado de yogur y fruta.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Cena<\/td>\n<td align=\"left\">\n<ul>\n<li>Crema de calabac\u00edn.<\/li>\n<li>Triturado de merluza con salsa verde.<\/li>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/manzana-al-microondas-con-canela\/\" target=\"_blank\" rel=\"noopener\">Manzana en el microondas con canela.<\/a><\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li><a href=\"https:\/\/oncoalicia.com\/es\/recetas\/sopa-de-tomate-con-aguacate\/\" target=\"_blank\" rel=\"noopener\">Sopa de tomate y albahaca.<\/a><\/li>\n<li>Triturado de tortilla de patatas.<\/li>\n<li>Yogur natural batido.<\/li>\n<\/ul>\n<\/td>\n<td align=\"left\">\n<ul>\n<li>Triturado de jud\u00edas verdes y patatas.<\/li>\n<li>Triturado de salm\u00f3n con salsa de lim\u00f3n.<\/li>\n<li>Triturado de fruta fresca.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/table>\n<p>Se puede obtener m\u00e1s informaci\u00f3n y recetas en la <a href=\"https:\/\/alicia.cat\/?s=triturada&#038;lang=ca\" target=\"_blank\" rel=\"noopener\">Gu\u00eda Pr\u00e1ctica de Gastronom\u00eda Triturada<\/a> elaborada por la Fundaci\u00f3 Al\u00edcia.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La esofagitis se define como la inflamaci\u00f3n del es\u00f3fago, que provoca dolor al ingerir los alimentos. Aparece dada la cercan\u00eda del es\u00f3fago al pulm\u00f3n, especialmente durante el tratamiento con radioterapia. Normalmente se da de forma progresiva y perdura hasta pocas semanas despu\u00e9s de finalizar el tratamiento. En funci\u00f3n del dolor que aparezca con la ingesta&hellip; <a class=\"more-link\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/\">Seguir leyendo <span class=\"screen-reader-text\">Recomendaciones diet\u00e9tico-culinarias para el dolor en la degluci\u00f3n en el c\u00e1ncer de pulm\u00f3n<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":3892,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pulmon-dolor-al-deglutir.php","meta":{"footnotes":""},"class_list":["post-3907","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con esofagitis - Oncoalicia<\/title>\n<meta name=\"description\" content=\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo dolor en la degluci\u00f3n derivada del tratamiento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con esofagitis - Oncoalicia\" \/>\n<meta property=\"og:description\" content=\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo dolor en la degluci\u00f3n derivada del tratamiento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/\" \/>\n<meta property=\"og:site_name\" content=\"Oncoalicia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-28T10:22:39+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Pastel-de-pavo-y-verduras.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/\",\"name\":\"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con esofagitis - Oncoalicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Pastel-de-pavo-y-verduras.jpg\",\"datePublished\":\"2022-05-14T06:31:26+00:00\",\"dateModified\":\"2026-06-28T10:22:39+00:00\",\"description\":\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo dolor en la degluci\u00f3n derivada del tratamiento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/#primaryimage\",\"url\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Pastel-de-pavo-y-verduras.jpg\",\"contentUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Pastel-de-pavo-y-verduras.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/dolor-en-la-deglucion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipos de c\u00e1ncer\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer de pulm\u00f3n\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recomendaciones diet\u00e9tico-culinarias para el dolor en la degluci\u00f3n en el c\u00e1ncer de pulm\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"name\":\"Oncoal\u00edcia\",\"description\":\"Comer durante el Tratamiento del C\u00e1ncer\",\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\",\"name\":\"Oncoal\u00edcia\",\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"width\":300,\"height\":300,\"caption\":\"Oncoal\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con esofagitis - Oncoalicia","description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo dolor en la degluci\u00f3n derivada del tratamiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/","og_locale":"es_ES","og_type":"article","og_title":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con esofagitis - Oncoalicia","og_description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo dolor en la degluci\u00f3n derivada del tratamiento.","og_url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/","og_site_name":"Oncoalicia","article_modified_time":"2026-06-28T10:22:39+00:00","og_image":[{"url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Pastel-de-pavo-y-verduras.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/","url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/","name":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con esofagitis - Oncoalicia","isPartOf":{"@id":"https:\/\/oncoalicia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/#primaryimage"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/#primaryimage"},"thumbnailUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Pastel-de-pavo-y-verduras.jpg","datePublished":"2022-05-14T06:31:26+00:00","dateModified":"2026-06-28T10:22:39+00:00","description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo dolor en la degluci\u00f3n derivada del tratamiento.","breadcrumb":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/#primaryimage","url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Pastel-de-pavo-y-verduras.jpg","contentUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Pastel-de-pavo-y-verduras.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/dolor-en-la-deglucion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oncoalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tipos de c\u00e1ncer","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/"},{"@type":"ListItem","position":3,"name":"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer de pulm\u00f3n","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/"},{"@type":"ListItem","position":4,"name":"Recomendaciones diet\u00e9tico-culinarias para el dolor en la degluci\u00f3n en el c\u00e1ncer de pulm\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/oncoalicia.com\/es\/#website","url":"https:\/\/oncoalicia.com\/es\/","name":"Oncoal\u00edcia","description":"Comer durante el Tratamiento del C\u00e1ncer","publisher":{"@id":"https:\/\/oncoalicia.com\/es\/#organization"},"alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oncoalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/oncoalicia.com\/es\/#organization","name":"Oncoal\u00edcia","alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","url":"https:\/\/oncoalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","width":300,"height":300,"caption":"Oncoal\u00edcia"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/3907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/comments?post=3907"}],"version-history":[{"count":4,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/3907\/revisions"}],"predecessor-version":[{"id":11673,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/3907\/revisions\/11673"}],"up":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/3892"}],"wp:attachment":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/media?parent=3907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}