{"id":3978,"date":"2022-05-13T00:41:01","date_gmt":"2022-05-13T00:41:01","guid":{"rendered":"https:\/\/www.oncoalicia.com\/alimentacion-durante-el-tratamiento-del-cancer-de-cabeza-y-cuello\/perdida-del-apetito\/"},"modified":"2025-07-04T07:11:22","modified_gmt":"2025-07-04T07:11:22","slug":"perdida-del-apetito","status":"publish","type":"page","link":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/","title":{"rendered":"Recomendaciones diet\u00e9tico-culinarias para la p\u00e9rdida del apetito en el c\u00e1ncer de cabeza y cuello"},"content":{"rendered":"<section class=\"recetas m-top-20\">\n<div class=\"container\">\n<div class=\"row\">\n<h1 class=\"col-md-12 text-center title-receta\">\n P\u00e9rdida del apetito<br \/>\n      <\/h1>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-12 subtitle-mitos\">\n<p>La p\u00e9rdida del apetito, tambi\u00e9n llamada anorexia, es uno de los s\u00edntomas m\u00e1s habituales durante el tratamiento oncol\u00f3gico. Puede aparecer en cualquier momento del tratamiento o de la enfermedad. Es importante prestar especial atenci\u00f3n si se prolonga en el tiempo, porque puede condicionar el estado nutricional del paciente.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row p-40 w-60\">\n<div class=\"col-md-12 text-center\">\n<h2 class=\"h3 recomanem-efectes-cancer\">\u00bfQU\u00c9 TE RECOMENDAMOS?<\/h2>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-1\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Comer en las horas en que m\u00e1s apetezca. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-1\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Aprovechar el momento del d\u00eda con m\u00e1s apetito para incluir los alimentos m\u00e1s energ\u00e9ticos y nutritivos.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-2\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Asegurar que las comidas principales sean completas. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-2\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Asegurar siempre en el almuerzo y la cena la presencia de verduras (crudas o cocidas), farin\u00e1ceos (tub\u00e9rculos, cereales, legumbres) y alimentos proteicos (carne, pescado y huevos u otros alimentos ricos en prote\u00ednas, como la soja), tal y como se indica en el <a href=\"\/es\/recomendaciones-generales\/#plato\">m\u00e9todo del plato<\/a>. Aunque sea en peque\u00f1as cantidades, pudiendo utilizar un plato de postre como base.<\/p>\n<\/p><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                    <b>Algunas recetas sugeridas:<\/b>\n                  <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/espaguetis-con-tomates-salteados-y-huevo\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Espaguetis con tomates salteados y huevo\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/arroz-con-fricando-de-tofu\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/73.-Arros-amb-fricando-de-tofu.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Arroz con fricand\u00f3 de tofu\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/combi-de-pescado-patata-y-verdura-en-el-micro\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/04\/101.-V-Combi-de-pescado-patata-y-verduras-al-micro.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n &#8216;Combi&#8217; de pescado, patata y verdura en el micro\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-3\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Preparar elaboraciones de alta densidad nutricional. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-3\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Son aquellas que en muy poco volumen incluyen una gran cantidad de energ\u00eda y nutrientes.<\/p>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Se pueden tener preparadas croquetas de pollo o bacalao; empanadas (de carne, at\u00fan, huevo, queso, etc.), que se pueden tener congeladas y fre\u00edr o calentar al momento; pat\u00e9s nutritivos para untar unas tostadas o s\u00e1ndwiches; cremas y sopas energ\u00e9ticas, que se pueden conservar en la nevera y comer directamente (fr\u00edas o calientes), y finalmente preparaciones dulces, como postre o para comer entre horas, como flanes, p\u00fadines o yogures tipo griego.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                    <b>Algunas recetas sugeridas:<\/b>\n                  <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/croquetas-de-patata-y-carne\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Croquetas-de-patata-y-carne-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Croquetas de patata y carne\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/crema-de-aguacate-platano-y-nueces\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Crema-de-aguacate-pl-tano-y-nueces.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Crema de aguacate, pl\u00e1tano y nueces\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/flan-de-platano\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Flam-de-platan.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Flan de pl\u00e1tano\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Tambi\u00e9n se pueden enriquecer los platos para aumentar su densidad nutricional con alimentos de elevado contenido energ\u00e9tico y\/o proteico:\n<ul>\n<ol>Sopas y pur\u00e9s: a\u00f1adir queso rallado, leche en polvo, huevo duro, dados de jam\u00f3n serrano, pollo o pescado.<\/ol>\n<ol>Ensaladas, pastas, arroces, verduras y otros platos: enriquecerlos con quesos, mayonesa, at\u00fan, claras de huevo, fruta fresca, dados de jam\u00f3n serrano\u2026<\/ol>\n<ol>Leche: leche en polvo, cacao, miel.<\/ol>\n<ol>Yogur: a\u00f1adirle fruta fresca, fruta en alm\u00edbar, frutos secos, miel, cereales de desayuno, mermelada.<\/ol>\n<\/li>\n<\/ul><\/div>\n<div class=\"col-md-6 descrip\">\n                <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/12\/Enriquiments-energ%E9%96%A3ics.jpg\" width=\"100%\">\n              <\/div>\n<div class=\"col-md-6 descrip\">\n                <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/12\/Enriquiments-protecis.jpg\" width=\"100%\">\n              <\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                    <b>Algunas recetas sugeridas:<\/b>\n                  <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/pure-rapido-de-garbanzos-con-huevo\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Pur%E2%80%9A-r-pido-de-garbanzos-con-huevo.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Pur\u00e9 r\u00e1pido de garbanzos con huevo\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/pudin-de-pera-enriquecido\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/95.1-Pudin-de-pera-enriquecido-1-scaled-1-1536x2048.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Puding de pera (enriquecido)\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/helado-al-momento-de-frutos-rojos-enriquecido\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/11\/2.-Helado-al-momento-de-frutos-rojos.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Helado en el momento de frutas rojas (enriquecido)\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Preparar batidos completos con fruta fresca, l\u00e1cteos o bebidas vegetales, frutos secos, fruta<br \/>\n desecada, galletas&#8230;\n                  <\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                    <b>Algunas recetas sugeridas:<\/b>\n                  <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/batido-de-platano-y-avellanas\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/04\/65.-Batido-de-platano-y-avellanas.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Batido de pl\u00e1tano y copos de avena\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/batido-de-fresa-con-nueces\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/04\/66.-Batido-de-fresas-con-nueces.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Batido de fresa con nueces\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/batido-de-manzana-cocida\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/batidos2.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Batido de manzana cocida\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-4\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Tener a la vista alimentos f\u00e1ciles de comer. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-4\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Accesibles para ir picando; si se dejan en el campo visual, puede que se consuman con m\u00e1s frecuencia: uva, pl\u00e1tano, mandarinas, cerezas, fresas, un bol de palomitas o una bolsa de palitos (blancos, integrales o con semillas), unas galletas, frutos secos (nueces, avellanas, almendras, pi\u00f1ones, pistachos, anacardos\u2026) o fruta desecada (orejones, ciruelas, pasas, pl\u00e1tano, coco). Tambi\u00e9n yogures (natural, griego, rico en prote\u00ednas\u2026) o quesitos.<\/p>\n<\/p><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                    <b>Algunas recetas sugeridas:<\/b>\n                  <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/rocas-de-almendra-con-jengibre\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Rocas-almendra-1568x2195.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Rocas de almendra con jengibre\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/avellanas-garrapinadas-sin-azucar\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Avellanes-garrapinyades.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Avellanas garrapi\u00f1adas sin az\u00facar\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                    <a href=\"\/es\/recetas\/palomitas-condimentadas\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Palomitas-condimentadas.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Palomitas condimentadas\n                        <\/div>\n<\/p><\/div>\n<p>                    <\/a>\n                  <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-5\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Fijarse peque\u00f1as metas a lo largo del d\u00eda. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-5\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Aunque no se tenga apetito es relevante pensar en la necesidad de comer. No es tan importante la cantidad que se come en una sola toma, sino lo que se consigue acumular al final del d\u00eda, y para ello es importante plantear peque\u00f1os objetivos que se puedan cumplir a lo largo del d\u00eda.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-6\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Mantener una correcta hidrataci\u00f3n. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-6\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Es recomendable beber siempre fuera de las comidas y tomar l\u00edquidos m\u00e1s nutritivos, como zumos de fruta naturales o licuados de fruta y verdura.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-7\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Utilizar platos grandes y cuidar la presentaci\u00f3n. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-7\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Servir la comida en platos grandes dar\u00e1 la sensaci\u00f3n de que hay menor cantidad de comida, y esto puede facilitar la ingesta. Cuidar la presentaci\u00f3n con variedad de colores, texturas y olores tambi\u00e9n ayudar\u00e1 a mejorar su aceptaci\u00f3n.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Procurar que la comida no desprenda olores ni sabores fuertes.<\/h3>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-8\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Intentar mantenerse fuera de la zona de la cocina y pedir ayuda a familiares o amigos. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-8\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Tener preparados algunos platos para evitar cocinar cada d\u00eda.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-9\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Hacer ejercicio o caminar a lo largo del d\u00eda. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-9\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Puede ayudar a estimular el apetito.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-10\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Mantener una buena higiene bucal. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n        <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-10\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Para evitar sabores no deseados que se puedan relacionar posteriormente con determinadas comidas.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>P\u00e9rdida del apetito La p\u00e9rdida del apetito, tambi\u00e9n llamada anorexia, es uno de los s\u00edntomas m\u00e1s habituales durante el tratamiento oncol\u00f3gico. Puede aparecer en cualquier momento del tratamiento o de la enfermedad. Es importante prestar especial atenci\u00f3n si se prolonga en el tiempo, porque puede condicionar el estado nutricional del paciente. \u00bfQU\u00c9 TE RECOMENDAMOS? Comer&hellip; <a class=\"more-link\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/\">Seguir leyendo <span class=\"screen-reader-text\">Recomendaciones diet\u00e9tico-culinarias para la p\u00e9rdida del apetito en el c\u00e1ncer de cabeza y cuello<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":3890,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"cabeza-perdida-apetito.php","meta":{"footnotes":""},"class_list":["post-3978","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alimentaci\u00f3n para pacientes de c\u00e1ncer de cabeza y cuello con p\u00e9rdida del apetito - Oncoalicia<\/title>\n<meta name=\"description\" content=\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de cabeza y cuello que est\u00e9n sufriendo p\u00e9rdida del apetito derivada del tratamiento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentaci\u00f3n para pacientes de c\u00e1ncer de cabeza y cuello con p\u00e9rdida del apetito - Oncoalicia\" \/>\n<meta property=\"og:description\" content=\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de cabeza y cuello que est\u00e9n sufriendo p\u00e9rdida del apetito derivada del tratamiento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/\" \/>\n<meta property=\"og:site_name\" content=\"Oncoalicia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T07:11:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/\",\"name\":\"Alimentaci\u00f3n para pacientes de c\u00e1ncer de cabeza y cuello con p\u00e9rdida del apetito - Oncoalicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg\",\"datePublished\":\"2022-05-13T00:41:01+00:00\",\"dateModified\":\"2025-07-04T07:11:22+00:00\",\"description\":\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de cabeza y cuello que est\u00e9n sufriendo p\u00e9rdida del apetito derivada del tratamiento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/#primaryimage\",\"url\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg\",\"contentUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/perdida-del-apetito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipos de c\u00e1ncer\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer de cabeza y cuello\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/cabeza-y-cuello\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recomendaciones diet\u00e9tico-culinarias para la p\u00e9rdida del apetito en el c\u00e1ncer de cabeza y cuello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"name\":\"Oncoal\u00edcia\",\"description\":\"Comer durante el Tratamiento del C\u00e1ncer\",\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\",\"name\":\"Oncoal\u00edcia\",\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"width\":300,\"height\":300,\"caption\":\"Oncoal\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de cabeza y cuello con p\u00e9rdida del apetito - Oncoalicia","description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de cabeza y cuello que est\u00e9n sufriendo p\u00e9rdida del apetito derivada del tratamiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/","og_locale":"es_ES","og_type":"article","og_title":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de cabeza y cuello con p\u00e9rdida del apetito - Oncoalicia","og_description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de cabeza y cuello que est\u00e9n sufriendo p\u00e9rdida del apetito derivada del tratamiento.","og_url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/","og_site_name":"Oncoalicia","article_modified_time":"2025-07-04T07:11:22+00:00","og_image":[{"url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/","url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/","name":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de cabeza y cuello con p\u00e9rdida del apetito - Oncoalicia","isPartOf":{"@id":"https:\/\/oncoalicia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/#primaryimage"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/#primaryimage"},"thumbnailUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg","datePublished":"2022-05-13T00:41:01+00:00","dateModified":"2025-07-04T07:11:22+00:00","description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de cabeza y cuello que est\u00e9n sufriendo p\u00e9rdida del apetito derivada del tratamiento.","breadcrumb":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/#primaryimage","url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg","contentUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Espaguetis-con-tomates-aasados-y-huevo-I.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/perdida-del-apetito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oncoalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tipos de c\u00e1ncer","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/"},{"@type":"ListItem","position":3,"name":"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer de cabeza y cuello","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/cabeza-y-cuello\/"},{"@type":"ListItem","position":4,"name":"Recomendaciones diet\u00e9tico-culinarias para la p\u00e9rdida del apetito en el c\u00e1ncer de cabeza y cuello"}]},{"@type":"WebSite","@id":"https:\/\/oncoalicia.com\/es\/#website","url":"https:\/\/oncoalicia.com\/es\/","name":"Oncoal\u00edcia","description":"Comer durante el Tratamiento del C\u00e1ncer","publisher":{"@id":"https:\/\/oncoalicia.com\/es\/#organization"},"alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oncoalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/oncoalicia.com\/es\/#organization","name":"Oncoal\u00edcia","alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","url":"https:\/\/oncoalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","width":300,"height":300,"caption":"Oncoal\u00edcia"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/3978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/comments?post=3978"}],"version-history":[{"count":0,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/3978\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/3890"}],"wp:attachment":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/media?parent=3978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}