{"id":4025,"date":"2022-05-14T19:48:07","date_gmt":"2022-05-14T19:48:07","guid":{"rendered":"https:\/\/www.oncoalicia.com\/alimentacion-durante-el-tratamiento-del-cancer-de-pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/"},"modified":"2025-07-04T07:43:05","modified_gmt":"2025-07-04T07:43:05","slug":"disminucion-o-desaparicion-del-gusto","status":"publish","type":"page","link":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/","title":{"rendered":"Recomendaciones diet\u00e9tico-culinarias para la disminuci\u00f3n del sabor en el c\u00e1ncer de pulm\u00f3n"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-md-12 subtitle-mitos\">\n<p>Se denominan hipogeusia y ageusia, respectivamente, y hacen referencia a la disminuci\u00f3n y a la desaparici\u00f3n de la capacidad de detectar los sabores de los alimentos.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row p-40 w-60\">\n<div class=\"col-md-12 text-center\">\n<h2 class=\"h3 recomanem-efectes-cancer\">\u00bfQU\u00c9 TE RECOMENDAMOS?<\/h2>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Mantener una higiene bucal correcta.<\/h3>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-1\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Aumentar la condimentaci\u00f3n de los alimentos con especias y\/o hierbas arom\u00e1ticas. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-1\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Podemos utilizar menta, albahaca, or\u00e9gano, tomillo, laurel, hinojo, ajo, zumos c\u00edtricos, sal (siempre que no est\u00e9 contraindicada) o potenciadores del sabor (dados de caldo).<\/p>\n<\/p><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algunas recetas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/dados-de-pescado-adobado-y-frito\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Dados-de-pescado-adobado-y-frito.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Dados de pescado encurtido y frito\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/ceviche\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/CEVICHE.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Ceviche\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/tabule\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Tabouleh.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Tabule\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/pollo-al-curri-con-arroz-y-manzana\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Pollo-al-curri-con-arroz-y-manzana.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Pollo al curry cono arroz y manzana\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Escoger sabores fuertes, como el queso, y mezclarlos con cremas o verduras para potenciar su sabor.<\/h3>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-2\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Masticar lentamente. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-2\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Ayuda a liberar los sabores y aumentar la producci\u00f3n de saliva.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Escoger alimentos l\u00edquidos o jugosos, ya que favorecen la disoluci\u00f3n de los sabores y la entrada de estos en las papilas gustativas.<\/h3>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-8\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Potenciar las preparaciones con los diferentes gustos b\u00e1sicos. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-8\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Puede ser que se disminuya la percepci\u00f3n de alg\u00fan sabor por encima de otros. Se recomienda comprovar cu\u00e1les est\u00e1n alterados o disminu\u00eddos (\u00e1cido, amargo, dulce, salado, umami) y as\u00ed potenciar elaboracioones con aquellos que mejor se perciban.<br \/>\nUtiliza esta <a href=\"\/es\/recetas\/empedrado-al-gusto\/\">receta<\/a> como ejemplo para adaptar los platos a diferentes gustos b\u00e1sicos.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Intentar detectar si hay alg\u00fan alimento o grupos de alimentos con mayor impacto.<\/h3>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se denominan hipogeusia y ageusia, respectivamente, y hacen referencia a la disminuci\u00f3n y a la desaparici\u00f3n de la capacidad de detectar los sabores de los alimentos. \u00bfQU\u00c9 TE RECOMENDAMOS? Mantener una higiene bucal correcta. Aumentar la condimentaci\u00f3n de los alimentos con especias y\/o hierbas arom\u00e1ticas. Podemos utilizar menta, albahaca, or\u00e9gano, tomillo, laurel, hinojo, ajo, zumos&hellip; <a class=\"more-link\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/\">Seguir leyendo <span class=\"screen-reader-text\">Recomendaciones diet\u00e9tico-culinarias para la disminuci\u00f3n del sabor en el c\u00e1ncer de pulm\u00f3n<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4022,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pulmon-disminucion-o-desaparicion-del-sabor.php","meta":{"footnotes":""},"class_list":["post-4025","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con disminuci\u00f3n del sabor - Oncoalicia<\/title>\n<meta name=\"description\" content=\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo disminuci\u00f3n o desaparici\u00f3n del sabor derivada del tratamiento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con disminuci\u00f3n del sabor - Oncoalicia\" \/>\n<meta property=\"og:description\" content=\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo disminuci\u00f3n o desaparici\u00f3n del sabor derivada del tratamiento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/\" \/>\n<meta property=\"og:site_name\" content=\"Oncoalicia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T07:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Dados-de-pescado-adobado-y-frito.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/\",\"name\":\"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con disminuci\u00f3n del sabor - Oncoalicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Dados-de-pescado-adobado-y-frito.jpg\",\"datePublished\":\"2022-05-14T19:48:07+00:00\",\"dateModified\":\"2025-07-04T07:43:05+00:00\",\"description\":\"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo disminuci\u00f3n o desaparici\u00f3n del sabor derivada del tratamiento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/#primaryimage\",\"url\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Dados-de-pescado-adobado-y-frito.jpg\",\"contentUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Dados-de-pescado-adobado-y-frito.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/disminucion-o-desaparicion-del-gusto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipos de c\u00e1ncer\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer de pulm\u00f3n\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recomendaciones diet\u00e9tico-culinarias para la alteraci\u00f3n del sabor en el c\u00e1ncer de pulm\u00f3n\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/pulmon\\\/alteracion-del-gusto\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Recomendaciones diet\u00e9tico-culinarias para la disminuci\u00f3n del sabor en el c\u00e1ncer de pulm\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"name\":\"Oncoal\u00edcia\",\"description\":\"Comer durante el Tratamiento del C\u00e1ncer\",\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\",\"name\":\"Oncoal\u00edcia\",\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"width\":300,\"height\":300,\"caption\":\"Oncoal\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con disminuci\u00f3n del sabor - Oncoalicia","description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo disminuci\u00f3n o desaparici\u00f3n del sabor derivada del tratamiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/","og_locale":"es_ES","og_type":"article","og_title":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con disminuci\u00f3n del sabor - Oncoalicia","og_description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo disminuci\u00f3n o desaparici\u00f3n del sabor derivada del tratamiento.","og_url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/","og_site_name":"Oncoalicia","article_modified_time":"2025-07-04T07:43:05+00:00","og_image":[{"url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Dados-de-pescado-adobado-y-frito.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/","url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/","name":"Alimentaci\u00f3n para pacientes de c\u00e1ncer de pulm\u00f3n con disminuci\u00f3n del sabor - Oncoalicia","isPartOf":{"@id":"https:\/\/oncoalicia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/#primaryimage"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/#primaryimage"},"thumbnailUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Dados-de-pescado-adobado-y-frito.jpg","datePublished":"2022-05-14T19:48:07+00:00","dateModified":"2025-07-04T07:43:05+00:00","description":"Consulta las recomendaciones alimentarias para personas con c\u00e1ncer de pulm\u00f3n que est\u00e9n sufriendo disminuci\u00f3n o desaparici\u00f3n del sabor derivada del tratamiento.","breadcrumb":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/#primaryimage","url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Dados-de-pescado-adobado-y-frito.jpg","contentUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Dados-de-pescado-adobado-y-frito.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/disminucion-o-desaparicion-del-gusto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oncoalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tipos de c\u00e1ncer","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/"},{"@type":"ListItem","position":3,"name":"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer de pulm\u00f3n","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/"},{"@type":"ListItem","position":4,"name":"Recomendaciones diet\u00e9tico-culinarias para la alteraci\u00f3n del sabor en el c\u00e1ncer de pulm\u00f3n","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/pulmon\/alteracion-del-gusto\/"},{"@type":"ListItem","position":5,"name":"Recomendaciones diet\u00e9tico-culinarias para la disminuci\u00f3n del sabor en el c\u00e1ncer de pulm\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/oncoalicia.com\/es\/#website","url":"https:\/\/oncoalicia.com\/es\/","name":"Oncoal\u00edcia","description":"Comer durante el Tratamiento del C\u00e1ncer","publisher":{"@id":"https:\/\/oncoalicia.com\/es\/#organization"},"alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oncoalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/oncoalicia.com\/es\/#organization","name":"Oncoal\u00edcia","alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","url":"https:\/\/oncoalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","width":300,"height":300,"caption":"Oncoal\u00edcia"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/4025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/comments?post=4025"}],"version-history":[{"count":0,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/4025\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/4022"}],"wp:attachment":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/media?parent=4025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}