{"id":8741,"date":"2024-06-04T21:50:32","date_gmt":"2024-06-04T21:50:32","guid":{"rendered":"https:\/\/oncoalicia.com\/?page_id=8741"},"modified":"2025-07-04T07:19:17","modified_gmt":"2025-07-04T07:19:17","slug":"asegurar-la-ingesta-de-calcio-y-vitamina-d","status":"publish","type":"page","link":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/","title":{"rendered":"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de una gastrectom\u00eda"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-md-12 subtitle-mitos\">\n<p>La osteoporosis es una enfermedad que se caracteriza por la disminuci\u00f3n de la densidad y calidad \u00f3seas, y la osteomalacia, una afecci\u00f3n que provoca que los huesos se vuelvan blandos y deformes. Ambas situaciones comportan un aumento del riesgo de sufrir fracturas, dolores \u00f3seos y debilidad muscular. La gastrectom\u00eda favorece el desarrollo de estas enfermedades a largo plazo, debido a una malabsorci\u00f3n de la vitamina D y el calcio, y tambi\u00e9n a su baja ingesta. En cuanto a la alimentaci\u00f3n, una vez normalizada y en funci\u00f3n de la tolerancia a diferentes alimentos, hay que tener en cuenta:<\/p>\n<\/p><\/div>\n<\/div>\n<div class=\"row p-40 w-60\">\n<div class=\"col-md-12 text-center\">\n<h2 class=\"h3 recomanem-efectes-cancer\">\u00bfQU\u00c9 TE RECOMENDAMOS?<\/h2>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" role=\"button\" href=\"#collapseExample-1\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Llevar a cabo una alimentaci\u00f3n suficiente, variada y equilibrada, adaptada a la nueva situaci\u00f3n. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><\/a><\/h3>\n<div id=\"collapseExample-1\" class=\"collapse\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Rev\u00edsese el apartado \u201cRecomendaciones diet\u00e9tico-culinarias despu\u00e9s de la gastrectom\u00eda (parcial o total)\u201d. <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" role=\"button\" href=\"#collapseExample-2\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Evitar el consumo de alcohol, tabaco y caf\u00e9, y moderar el consumo de sal. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><\/a><\/h3>\n<div id=\"collapseExample-2\" class=\"collapse\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Se pueden consumir peque\u00f1as cantidades de caf\u00e9, siempre con leche sin lactosa o bebidas vegetales enriquecidas con calcio o vitamina D. <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" role=\"button\" href=\"#collapseExample-3\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Asegurar una ingesta diaria adecuada de alimentos fuente de prote\u00ednas, calcio, magnesio y vitamina D. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><\/a><\/h3>\n<div id=\"collapseExample-3\" class=\"collapse\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Todos ellos juegan un papel importante en la prevenci\u00f3n de la p\u00e9rdida de masa muscular y \u00f3sea.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" role=\"button\" href=\"#collapseExample-4\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Fuentes de calcio. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><\/a><\/h3>\n<div id=\"collapseExample-4\" class=\"collapse\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>El calcio lo podemos encontrar tanto en alimentos de origen animal como vegetal, y hay que incorporarlo en el formato recomendado para la gastrectom\u00eda y seg\u00fan tolerancia y evoluci\u00f3n (leche sin lactosa, frutos secos molidos o en crema 100% de frutos secos, legumbres en pur\u00e9 o bien aplastadas con el tenedor, pescado azul seg\u00fan tolerancia y progresi\u00f3n). <\/p>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<table class=\"table\">\n<tr>\n<td class=\"table-txt\">\n<table>\n<tr>\n<td>Principales fuentes de calcio de origen animal <\/td>\n<td>Principales fuentes de calcio de origen vegetal <\/td>\n<\/tr>\n<tr>\n<td>\n<ul>\n<li>Alimentos l\u00e1cteos (leche, yogur, quesos\u2026) <\/li>\n<li>Pescado con espinas blandas comestibles triturado (como la sardina y el boquer\u00f3n, frescos y\/o enlatados) *  <\/li>\n<li>Alimentos enriquecidos** con este mineral <\/li>\n<\/ul>\n<\/td>\n<td>\n<ul>\n<li>Frutos secos (nueces, avellanas, almendras)<\/li>\n<li>Legumbres (garbanzos, soja, lentejas, alubias) y derivados (tofu) <\/li>\n<li>Vegetales de hoja verde (espinacas, acelgas, col, br\u00f3coli\u2026) <\/li>\n<li>Alimentos enriquecidos** con este mineral <\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<div class=\"col-md-12 descrip\">\n<p>* Se pueden consumir pescados con espinas solo en forma triturada. <br \/>**Los alimentos enriquecidos con calcio, como algunos cereales de desayuno, galletas o bebidas vegetales, son opciones v\u00e1lidas siempre que no contengan mucho az\u00facar. <\/p>\n<\/p><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                                <b>Algunas recetas sugeridas:<\/b>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/receptes\/rocas-de-almendra-con-jengibre\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Rocas-almendra-1568x2195.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Rocas de almendra con jengibre\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/copa-de-yogur-con-menta\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/yogur-con-menta-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Copa de yogur con menta<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/pure-rapido-de-garbanzos-con-huevo\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Pur%E2%80%9A-r-pido-de-garbanzos-con-huevo.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Pur\u00e9 r\u00e1pido de garbanzos con huevo<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/hamburguesa-de-garbanzos\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Hamburguesa-de-garbanzos-1568x2195.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Hamburguesa de garbanzos<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/bizcocho-en-el-microondas-con-nueces-y-zanahoria\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/10\/Bizcocho-al-microondas-con-nueces-y-zanahoria.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Bizcocho en el microondas con nueces y zanahoria<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/arroz-con-fricando-de-tofu-textura-modificada\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Arroz-con-fricanda-de-tofu-tm-II.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Arroz con fricand\u00f3 de tofu (textura modificada)<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/berenjena-con-tofu-textura-modificada\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/04\/106.1-Berenjena-con-tofu-textura-modificada.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Berenjena con tofu (textura modificada)<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/pudin-de-pera-enriquecido\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/95.1-Pudin-de-pera-enriquecido-1-scaled-1-1568x2091.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Pudin de pera (enriquecido)\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/helado-al-momento-de-platano-y-manzana-enriquecido\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Helado-al-momento-pera-manzana-platano.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Helado al momento de pl\u00e1tano y manzana (enriquecido)<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<p>V\u00e9anse m\u00e1s recetas introduciendo osteoporosis y gastrectom\u00eda en el buscador, junto con cualquier otro efecto secundario que se presente. <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" role=\"button\" href=\"#collapseExample-5\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Fuentes de vitamina D. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><\/a><\/h3>\n<div id=\"collapseExample-5\" class=\"collapse\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Las mejores fuentes son el pescado graso* (salm\u00f3n, at\u00fan, sardinas, boquerones, caballa&#8230;), los l\u00e1cteos (leche sin lactosa y resto de l\u00e1cteos, como yogur natural o quesos, seg\u00fan tolerancia), la yema de huevo, las setas y los alimentos enriquecidos** con esta vitamina.<br \/>\n                            <br \/>Ejemplos de recetas ricas en vitamina D que podr\u00e1 incorporar o adaptar seg\u00fan tolerancia y progresi\u00f3n: <\/p>\n<\/p><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                                <b>Algunas recetas sugeridas:<\/b>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/ensalada-tibia-de-salmon-y-manzana\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Ensalada-t%E0%B8%81bia-de-salm%E0%B8%82n-y-manzana-1568x2195.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Ensalada tibia de salm\u00f3n y manzana<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/copa-de-yogur-con-menta\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/yogur-con-menta-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Copa de yogur con menta<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/escabeche-de-caballa-con-naranja\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Escabeche-de-caballa-con-naranja-1568x2195.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Escabeche de caballa con naranja<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/champizzes\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Champizzas-1568x2195.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            \u2018Champizzas\u2019<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/ensalada-de-tres-cereales-con-salmon\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Ensalada-tres-cereales-con-salmon.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Ensalada de tres cereales con salm\u00f3n<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/rolls-de-tortilla\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Rolls-tortilla.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            \u2018Rolls\u2019 de tortilla<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/flan-de-huevo-y-manzana-rico-en-proteina\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/10\/Flan-de-huevo-y-manzana-rico-en-proteinas.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Flan de huevo y manzana rico en prote\u00edna<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/tortilla-de-patatas-y-cebolla-textura-modificada\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/10\/Tortilla-de-patatas-y-cebolla-textura-modificada.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Tortilla de patatas y cebolla (textura modificada)<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/salsa-de-setas-para-enriquecer\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2024\/05\/Salsa-de-setas-para-enriqucer-1568x1254.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Salsa de setas para enriquecer<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-2 col-sm-6 text-center recetitas\"><\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/huevos-rellenos-textura-modificada\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/10\/Huevos-rellenos-textura-modificada.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Huevos rellenos (textura modificada)<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/es\/recetas\/pastel-de-pescado\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Pastel-de-pescado.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n                                            Pastel de pescado<\/p><\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-2 col-sm-6 text-center recetitas\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<p>V\u00e9anse m\u00e1s recetas introduciendo osteoporosis y gastrectom\u00eda en el buscador, junto con cualquier otro efecto secundario que se presente.<br \/>\n                            <br \/>*Tener especial precauci\u00f3n con las espinas.<br \/>\n                            <br \/>**Los alimentos enriquecidos con vitamina D, como algunos cereales de desayuno, galletas o bebidas vegetales, son opciones v\u00e1lidas siempre que no contengan mucho az\u00facar. <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" role=\"button\" href=\"#collapseExample-6\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Realizar actividad f\u00edsica de manera regular. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><\/a><\/h3>\n<div id=\"collapseExample-6\" class=\"collapse\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Se recomienda realizarla de manera regular, ya que es un elemento clave en la prevenci\u00f3n de la osteoporosis: caminar 30 minutos al d\u00eda con una exposici\u00f3n al sol durante 10-15 minutos en verano y 20-30 minutos en invierno, preferentemente por la ma\u00f1ana y unas tres veces por semana, siempre con protecci\u00f3n solar.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La osteoporosis es una enfermedad que se caracteriza por la disminuci\u00f3n de la densidad y calidad \u00f3seas, y la osteomalacia, una afecci\u00f3n que provoca que los huesos se vuelvan blandos y deformes. Ambas situaciones comportan un aumento del riesgo de sufrir fracturas, dolores \u00f3seos y debilidad muscular. La gastrectom\u00eda favorece el desarrollo de estas enfermedades&hellip; <a class=\"more-link\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/\">Seguir leyendo <span class=\"screen-reader-text\">Asegurar la ingesta de calcio y vitamina D despu\u00e9s de una gastrectom\u00eda<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":8733,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8741","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asegurar la ingesta de calcio y vitamina D despu\u00e9s de la gastrectom\u00eda - Oncoalicia<\/title>\n<meta name=\"description\" content=\"Despu\u00e9s de una gastrectom\u00eda es muy importante asegurar la ingesta de alimentos ricos en calcio y vitamina D.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de la gastrectom\u00eda - Oncoalicia\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de una gastrectom\u00eda es muy importante asegurar la ingesta de alimentos ricos en calcio y vitamina D.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/\" \/>\n<meta property=\"og:site_name\" content=\"Oncoalicia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T07:19:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Rocas-almendra-1568x2195.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/\",\"name\":\"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de la gastrectom\u00eda - Oncoalicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Rocas-almendra-1568x2195.jpg\",\"datePublished\":\"2024-06-04T21:50:32+00:00\",\"dateModified\":\"2025-07-04T07:19:17+00:00\",\"description\":\"Despu\u00e9s de una gastrectom\u00eda es muy importante asegurar la ingesta de alimentos ricos en calcio y vitamina D.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Rocas-almendra-1568x2195.jpg\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Rocas-almendra-1568x2195.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/asegurar-la-ingesta-de-calcio-y-vitamina-d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipos de c\u00e1ncer\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer g\u00e1strico\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recomendaciones diet\u00e9tico-culinarias despu\u00e9s de una gastrectom\u00eda\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/tipos-de-cancer\\\/gastrico\\\/tras-el-alta-hospitalaria-postcirugia\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de una gastrectom\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"name\":\"Oncoal\u00edcia\",\"description\":\"Comer durante el Tratamiento del C\u00e1ncer\",\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#organization\",\"name\":\"Oncoal\u00edcia\",\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"width\":300,\"height\":300,\"caption\":\"Oncoal\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de la gastrectom\u00eda - Oncoalicia","description":"Despu\u00e9s de una gastrectom\u00eda es muy importante asegurar la ingesta de alimentos ricos en calcio y vitamina D.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/","og_locale":"es_ES","og_type":"article","og_title":"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de la gastrectom\u00eda - Oncoalicia","og_description":"Despu\u00e9s de una gastrectom\u00eda es muy importante asegurar la ingesta de alimentos ricos en calcio y vitamina D.","og_url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/","og_site_name":"Oncoalicia","article_modified_time":"2025-07-04T07:19:17+00:00","og_image":[{"url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Rocas-almendra-1568x2195.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/","url":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/","name":"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de la gastrectom\u00eda - Oncoalicia","isPartOf":{"@id":"https:\/\/oncoalicia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/#primaryimage"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/#primaryimage"},"thumbnailUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Rocas-almendra-1568x2195.jpg","datePublished":"2024-06-04T21:50:32+00:00","dateModified":"2025-07-04T07:19:17+00:00","description":"Despu\u00e9s de una gastrectom\u00eda es muy importante asegurar la ingesta de alimentos ricos en calcio y vitamina D.","breadcrumb":{"@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/#primaryimage","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Rocas-almendra-1568x2195.jpg","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/03\/Rocas-almendra-1568x2195.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/asegurar-la-ingesta-de-calcio-y-vitamina-d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oncoalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tipos de c\u00e1ncer","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/"},{"@type":"ListItem","position":3,"name":"Recomendaciones alimentarias durante el tratamiento del c\u00e1ncer g\u00e1strico","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/"},{"@type":"ListItem","position":4,"name":"Recomendaciones diet\u00e9tico-culinarias despu\u00e9s de una gastrectom\u00eda","item":"https:\/\/oncoalicia.com\/es\/tipos-de-cancer\/gastrico\/tras-el-alta-hospitalaria-postcirugia\/"},{"@type":"ListItem","position":5,"name":"Asegurar la ingesta de calcio y vitamina D despu\u00e9s de una gastrectom\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/oncoalicia.com\/es\/#website","url":"https:\/\/oncoalicia.com\/es\/","name":"Oncoal\u00edcia","description":"Comer durante el Tratamiento del C\u00e1ncer","publisher":{"@id":"https:\/\/oncoalicia.com\/es\/#organization"},"alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oncoalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/oncoalicia.com\/es\/#organization","name":"Oncoal\u00edcia","alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","url":"https:\/\/oncoalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","width":300,"height":300,"caption":"Oncoal\u00edcia"},"image":{"@id":"https:\/\/oncoalicia.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/8741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/comments?post=8741"}],"version-history":[{"count":0,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/8741\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/pages\/8733"}],"wp:attachment":[{"href":"https:\/\/oncoalicia.com\/es\/wp-json\/wp\/v2\/media?parent=8741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}