{"id":6560,"date":"2022-05-12T00:58:05","date_gmt":"2022-05-12T00:58:05","guid":{"rendered":"https:\/\/oncoalicia.com\/?page_id=6560"},"modified":"2025-07-08T07:26:42","modified_gmt":"2025-07-08T07:26:42","slug":"boca-seca","status":"publish","type":"page","link":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/","title":{"rendered":"Recomenda\u00e7\u00f5es diet\u00e9ticas para a boca seca em c\u00e2ncer de mama"},"content":{"rendered":"<section class=\"recetas m-top-20\">\n<div class=\"container\">\n<div class=\"row\">\n<h1 class=\"col-md-12 text-center title-receta\">\n Boca seca<br \/>\n      <\/h1>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-12 subtitle-mitos\">\n<p>Denomina-se xerostomia e \u00e9 produzida por uma diminui\u00e7\u00e3o na qualidade e na quantidade de saliva segregada, causada habitualmente por alguns medicamentos utilizados no tratamento para o c\u00e2ncer de mama.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row p-40 w-60\">\n<div class=\"col-md-12 text-center\">\n<h2 class=\"h3 recomanem-efectes-cancer\">O QUE RECOMENDAMOS?<\/h2>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-1\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Enxaguar a boca antes das refei\u00e7\u00f5es e manter uma boa higiene bucal. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-1\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Podem-se utilizar solu\u00e7\u00f5es de \u00e1gua com bicarbonato, lim\u00e3o ou camomila.<br \/>\n\u00c9 importante escovar os dentes depois das refei\u00e7\u00f5es.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Lubrificar os l\u00e1bios com protetor labial.<\/h3>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-2\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Tomar l\u00edquidos frequentemente. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-2\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>\u00c9 recomend\u00e1vel levar consigo sempre uma garrafa de \u00e1gua pequena para poder tomar pequenos goles conforme a necessidade.<\/p>\n<ul>\n<li>Durante todo o dia, para ajudar a refrescar a boca e, ao mesmo tempo, hidratar-se. Tamb\u00e9m podem ser consumidos sorvetes ou raspadinhas caseiros, ou deixar que se desfa\u00e7am na boca cubinhos ou gelatinas elaborados com suco de fruta ou ch\u00e1s de hortel\u00e3 ou tomilho.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algumas receitas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/cha-de-frutas-vermelhas\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Infusi%E0%B8%82n-de-frutos-rojos.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Ch\u00e1 de frutas vermelhas\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/cubos-gelados-de-frutas-citricas\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Glacons-de-citrics.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Cubos gelados de frutas c\u00edtricas\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/picole-de-morango-e-laranja\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/04\/110.-V-Polo-de-fresa-y-naranja.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Picol\u00e9 de morango e laranja\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Durante as refei\u00e7\u00f5es, \u00e9 necess\u00e1rio facilitar a degluti\u00e7\u00e3o dos alimentos. Uma boa op\u00e7\u00e3o \u00e9 preparar uma limonada dilu\u00edda \u2014 um litro de \u00e1gua com o suco de um lim\u00e3o \u2014, que, al\u00e9m de ajudar a degluti\u00e7\u00e3o, pode ajudar a salivar um pouco mais.<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-3\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Consumir alimentos \u00e1cidos para estimular a produ\u00e7\u00e3o de saliva. (Desde que a condi\u00e7\u00e3o de boca seca n\u00e3o esteja acompanhada por feridas na boca e\/ou garganta) <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-3\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Entre as refei\u00e7\u00f5es, comer peda\u00e7os de fruta \u00e1cida, como o abacaxi ou a laranja. Mascar chiclete ou chupar balas sem a\u00e7\u00facar.<\/li>\n<li>Preparar pratos tanto frios como quentes, com alimentos \u00e1cidos como o tomate, o lim\u00e3o, as frutas vermelhas e outras frutas.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algumas receitas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/ceviche\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/CEVICHE.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Ceviche\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/sopa-de-tomate-e-manjericao\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Sopa-de-tomaquet-i-alfabrega.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Sopa de tomate e manjeric\u00e3o\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/creme-de-maracuja-chia-e-kiwi\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2023\/10\/Creme-de-maracuja-chia-e-kiwi-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Creme de maracuj\u00e1, chia e kiwi\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Adicionar um pouco de lim\u00e3o sobre as prepara\u00e7\u00f5es que o permitam, como um fil\u00e9 de peixe cozido.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algumas receitas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-2 col-sm-6 text-center recetitas\">\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n<a href=\"\/pt-br\/receitas\/papilote-de-peixe-magro-com-molho-de-limao\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/10.2-Papillote-de-pescado-con-salsa-de-limon-1-scaled-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Papilote de peixe magro com molho de lim\u00e3o\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/peixe-com-ervas-aromaticas-e-quibebe\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2023\/10\/Peixe-com-ervas-aromaticas-e-quibebe-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Peixe com ervas arom\u00e1ticas e quibebe\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-2 col-sm-6 text-center recetitas\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-4\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Considerar a textura e consist\u00eancia dos alimentos. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-4\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Incorporar \u00e0s refei\u00e7\u00f5es alimentos com alto conte\u00fado l\u00edquido, como pur\u00eas e cremes de legumes, sopas, pudins, pur\u00eas de frutas, fl\u00e3s, vitaminas de leite, gelatinas ou iogurtes.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algumas receitas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/sopa-de-tomilho\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Sopa-farigola.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Sopa de tomilho\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/creme-morno-de-abobora-laranja-e-gengibre\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Cremas-de-calabaza.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Creme morno de ab\u00f3bora, laranja e gengibre\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/vitamina-de-banana-e-avelas\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/04\/65.-Batido-de-platano-y-avellanas.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Vitamina de banana e avel\u00e3s\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-2 col-sm-6 text-center recetitas\">\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/mingau-de-tapioca-e-castanha-do-brasil\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2023\/10\/Mingau-de-tapioca-e-castanha-do-Brasil-3.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Mingau de tapioca e castanha-do-Brasil\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/creme-de-abacate-e-mel\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2023\/10\/creme-de-abacate-e-mel-2.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Creme de abacate e mel\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-2 col-sm-6 text-center recetitas\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Comer o arroz e a massa bem cozidos; os queijos que sejam frescos, tenros ou cremosos; as verduras pouco fibrosas e bem cozidas; a maioria dos peixes; as fritadas e os mexidos; algumas carnes macias, como a coxa de frango desfiada, a carne cozida, ou at\u00e9 mesmo os pudins ou bolos de carne; as frutas maduras e moles, cozidas ou em calda.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algumas receitas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/fla-de-banana\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Flam-de-platan.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Fl\u00e3 de banana\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/bolinho-de-peixe\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Pastel-de-pescado.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Bolinho de peixe\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/enroladinhos-de-tortilha\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Rolls-tortilla.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Enroladinhos de tortilha\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\"><\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/creme-de-arroz-e-feijao\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2023\/10\/creme-de-arroz-e-feijao-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Creme de Arroz e Feij\u00e3o (textura modificada)\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Adicionar molhos a algumas prepara\u00e7\u00f5es mais secas, como bechamel, vinagretes, maionese light etc.<\/li>\n<\/ul><\/div>\n<div class=\"col-md-12 text-center\">\n<div class=\"row\">\n<div class=\"col-md-12 recetas-sug\">\n                            <b>Algunas recetas sugeridas:<\/b>\n                          <\/div>\n<\/p><\/div>\n<div class=\"row\">\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/aspargos-cozidos-no-vapor-aos-tres-molhos\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/10.Esparragos-al-vapor.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Aspargos cozidos no vapor aos tr\u00eas molhos\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/papilote-de-peixe-magro-com-molho-verde\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/10.1-Papillote-de-pescado-con-salsa-verde-1-scaled-1.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Papilote de peixe magro com molho verde\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<div class=\"col-md-4 col-sm-6 text-center recetitas\">\n                                <a href=\"\/pt-br\/receitas\/minissanduiches-de-salmao\/\"><\/p>\n<div class=\"cuadro-receta-2 text-center\">\n                                        <img decoding=\"async\" src=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2021\/10\/Mini-sandvitxos-4.jpg\" class=\"w-50\"><\/p>\n<div class=\"txt-mito\">\n Minissandu\u00edches de salm\u00e3o\n                                        <\/div>\n<\/p><\/div>\n<p>                                <\/a>\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n<ul>\n<li>Evitar refei\u00e7\u00f5es espessas, grudentas, secas e fibrosas, como p\u00e3o, algumas carnes grelhadas, pur\u00ea de batatas muito espesso etc.<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Boca seca Denomina-se xerostomia e \u00e9 produzida por uma diminui\u00e7\u00e3o na qualidade e na quantidade de saliva segregada, causada habitualmente por alguns medicamentos utilizados no tratamento para o c\u00e2ncer de mama. O QUE RECOMENDAMOS? Enxaguar a boca antes das refei\u00e7\u00f5es e manter uma boa higiene bucal. Podem-se utilizar solu\u00e7\u00f5es de \u00e1gua com bicarbonato, lim\u00e3o ou&hellip; <a class=\"more-link\" href=\"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/\">Continue reading <span class=\"screen-reader-text\">Recomenda\u00e7\u00f5es diet\u00e9ticas para a boca seca em c\u00e2ncer de mama<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":6529,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"mama-boca-seca.php","meta":{"footnotes":""},"class_list":["post-6560","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de mama que apresentam boca seca - Oncoalicia<\/title>\n<meta name=\"description\" content=\"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de mama que est\u00e3o com boca seca devido ao tratamento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de mama que apresentam boca seca - Oncoalicia\" \/>\n<meta property=\"og:description\" content=\"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de mama que est\u00e3o com boca seca devido ao tratamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/\" \/>\n<meta property=\"og:site_name\" content=\"Oncoalicia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T07:26:42+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Infusi%E0%B8%82n-de-frutos-rojos.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/\",\"name\":\"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de mama que apresentam boca seca - Oncoalicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Infusi%E0%B8%82n-de-frutos-rojos.jpg\",\"datePublished\":\"2022-05-12T00:58:05+00:00\",\"dateModified\":\"2025-07-08T07:26:42+00:00\",\"description\":\"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de mama que est\u00e3o com boca seca devido ao tratamento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/#primaryimage\",\"url\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Infusi%E0%B8%82n-de-frutos-rojos.jpg\",\"contentUrl\":\"http:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Infusi%E0%B8%82n-de-frutos-rojos.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/boca-seca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipos de c\u00e2ncer\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recomenda\u00e7\u00f5es alimentares durante o tratamento do c\u00e2ncer de mama\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/mama\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recomenda\u00e7\u00f5es diet\u00e9ticas para a boca seca em c\u00e2ncer de mama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/\",\"name\":\"Oncoal\u00edcia\",\"description\":\"Comer durante el Tratamiento del C\u00e1ncer\",\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#organization\"},\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#organization\",\"name\":\"Oncoal\u00edcia\",\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"width\":300,\"height\":300,\"caption\":\"Oncoal\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de mama que apresentam boca seca - Oncoalicia","description":"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de mama que est\u00e3o com boca seca devido ao tratamento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/","og_locale":"pt_BR","og_type":"article","og_title":"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de mama que apresentam boca seca - Oncoalicia","og_description":"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de mama que est\u00e3o com boca seca devido ao tratamento.","og_url":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/","og_site_name":"Oncoalicia","article_modified_time":"2025-07-08T07:26:42+00:00","og_image":[{"url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Infusi%E0%B8%82n-de-frutos-rojos.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/","url":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/","name":"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de mama que apresentam boca seca - Oncoalicia","isPartOf":{"@id":"https:\/\/oncoalicia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/#primaryimage"},"image":{"@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/#primaryimage"},"thumbnailUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Infusi%E0%B8%82n-de-frutos-rojos.jpg","datePublished":"2022-05-12T00:58:05+00:00","dateModified":"2025-07-08T07:26:42+00:00","description":"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de mama que est\u00e3o com boca seca devido ao tratamento.","breadcrumb":{"@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/#primaryimage","url":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Infusi%E0%B8%82n-de-frutos-rojos.jpg","contentUrl":"http:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/02\/Infusi%E0%B8%82n-de-frutos-rojos.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/boca-seca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oncoalicia.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Tipos de c\u00e2ncer","item":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/"},{"@type":"ListItem","position":3,"name":"Recomenda\u00e7\u00f5es alimentares durante o tratamento do c\u00e2ncer de mama","item":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/mama\/"},{"@type":"ListItem","position":4,"name":"Recomenda\u00e7\u00f5es diet\u00e9ticas para a boca seca em c\u00e2ncer de mama"}]},{"@type":"WebSite","@id":"https:\/\/oncoalicia.com\/pt-br\/#website","url":"https:\/\/oncoalicia.com\/pt-br\/","name":"Oncoal\u00edcia","description":"Comer durante el Tratamiento del C\u00e1ncer","publisher":{"@id":"https:\/\/oncoalicia.com\/pt-br\/#organization"},"alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oncoalicia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oncoalicia.com\/pt-br\/#organization","name":"Oncoal\u00edcia","alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","url":"https:\/\/oncoalicia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oncoalicia.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","width":300,"height":300,"caption":"Oncoal\u00edcia"},"image":{"@id":"https:\/\/oncoalicia.com\/pt-br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages\/6560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=6560"}],"version-history":[{"count":0,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages\/6560\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages\/6529"}],"wp:attachment":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=6560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}