{"id":6698,"date":"2022-05-14T08:45:57","date_gmt":"2022-05-14T06:45:57","guid":{"rendered":"https:\/\/oncoalicia.com\/?page_id=6698"},"modified":"2026-06-27T11:49:09","modified_gmt":"2026-06-27T09:49:09","slug":"dificuldade-para-deglutir-liquidos","status":"publish","type":"page","link":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/","title":{"rendered":"Recomenda\u00e7\u00f5es diet\u00e9ticas para a dificuldade para deglutir l\u00edquidos em c\u00e2ncer de pulm\u00e3o"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-md-12 subtitle-mitos\">\n<p>Caracteriza-se por tosse ou pigarro com sensa\u00e7\u00e3o de engasgo posterior \u00e0 ingest\u00e3o de \u00e1gua ou outros l\u00edquidos. \u00c0s vezes, s\u00e3o produzidas tamb\u00e9m altera\u00e7\u00f5es na voz ap\u00f3s a degluti\u00e7\u00e3o. Recomenda-se modificar e adaptar a viscosidade\/textura dos l\u00edquidos, incluindo a \u00e1gua, para evitar que esses l\u00edquidos acabem sendo aspirados para o pulm\u00e3o e provoquem infec\u00e7\u00f5es pulmonares que podem ser perigosas.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"row p-40 w-60\">\n<div class=\"col-md-12 text-center\">\n<h2 class=\"h3 recomanem-efectes-cancer\">O QUE RECOMENDAMOS?<\/h2>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-3\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Adaptar os l\u00edquidos \u00e0 viscosidade\/textura que melhor se adeque \u00e0s necessidades espec\u00edficas do paciente. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-3\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Atualmente podem-se indicar tr\u00eas tipos de viscosidades diferentes conforme o grau de disfagia para l\u00edquidos apresentado: n\u00e9ctar, mel ou pudim. O fonaudi\u00f3logo de refer\u00eancia indicar\u00e1 qual \u00e9 a viscosidade espec\u00edfica que dever\u00e1 ser seguida para cada caso.<\/p>\n<\/p><\/div>\n<div class=\"col-md-12\">\n<table class=\"table\">\n<tr>\n<td class=\"table-title\">Classifica\u00e7\u00e3o de viscosidade para disfagia para l\u00edquidos<\/td>\n<\/tr>\n<tr>\n<td class=\"table-txt\">\n<table>\n<tr>\n<td><strong>Viscosidade<\/strong><\/td>\n<td><strong>Exemplos de bebidas e alimentos<\/strong><\/td>\n<\/tr>\n<tr>\n<td>\n                                        <b>N\u00e9ctar<\/b><br \/>\nTextura similar ao suco de p\u00eassego.<br \/>\nPode-se beber com canudinho ou em copo.<br \/>\nQuando o n\u00e9ctar escorre de uma colher forma um filamento fino.\n                                      <\/td>\n<td align=\"left\">\nSuco de tomate, suco de p\u00eassego, cremes de legumes, gaspacho (sopa fria t\u00edpica na Espanha), iogurtes l\u00edquidos para beber.\n                                      <\/td>\n<\/tr>\n<tr>\n<td>\n                                        <b>Mel<\/b><br \/>\nTextura semelhante ao mel.<br \/>\nN\u00e3o \u00e9 poss\u00edvel beber com canudinho, mas sim em um copo.<br \/>\nQuando o mel escorre de uma colher, forma gotas grandes.\n                                      <\/td>\n<td align=\"left\">\nIogurte batido, mingaus\n                                      <\/td>\n<\/tr>\n<tr>\n<td>\n                                        <b>Pudim<\/b><br \/>\nTextura de fl\u00e3 ou pudim.<br \/>\nIngere-se somente com colher.<br \/>\nQuando o pudim escorre de uma colher, cai como uma massa.\n                                      <\/td>\n<td align=\"left\">\nFl\u00e3, coalhada, requeij\u00e3o\n                                      <\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-7\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Garantir uma hidrata\u00e7\u00e3o correta, adaptando os l\u00edquidos \u00e0 viscosidade necess\u00e1ria com a ajuda de espessantes comerciais. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-7\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Devem-se seguir sempre as instru\u00e7\u00f5es do espessante em todos os l\u00edquidos que ser\u00e3o ingeridos, j\u00e1 que existem diferentes tipos de espessantes comerciais:<\/p>\n<\/p><\/div>\n<div class=\"col-md-12\">\n<table class=\"table\">\n<tr>\n<td class=\"table-title\">Aspectos a serem considerados ao espessar bebidas com espessantes comerciais<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" class=\"table-txt\">\n<ul>\n<li>A dosagem indicada na embalagem corresponde \u00e0 quantidade necess\u00e1ria para conseguir a viscosidade desejada em \u00e1gua. Se espessamos outra bebida, a dosagem para a mesma viscosidade pode variar.<\/li>\n<li>\u00c9 importante respeitar o tempo que o espessante necessita para exercer sua fun\u00e7\u00e3o. Esse tempo pode variar tamb\u00e9m em fun\u00e7\u00e3o do l\u00edquido e da temperatura deste, portanto se recomenda espessar a bebida \u00e0 temperatura de consumo, respeitando o tempo de a\u00e7\u00e3o, mas sempre consumi-la no per\u00edodo indicado. Assim, evitaremos modifica\u00e7\u00f5es da viscosidade em virtude de uma mudan\u00e7a de temperatura  ou pelo tempo em repouso antes do consumo.<\/li>\n<li>3.\tSempre que se quiser acrescentar algum ingrediente \u00e0 bebida para sua dissolu\u00e7\u00e3o ou ainda misturar bebidas diferentes, \u00e9 necess\u00e1rio faz\u00ea-lo antes de acrescentar o espessante. Nunca se deve espessar uma bebida e acrescentar posteriormente outro ingrediente.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<table>\n<tr>\n<td>Sucos<\/td>\n<td align=\"left\">\n<ul>\n<li>A viscosidade original de um suco n\u00e3o \u00e9 sempre totalmente l\u00edquida, por isso podemos necessitar de uma dosagem menor que a indicada na embalagem para conseguir a viscosidade desejada.<\/li>\n<li>Em fun\u00e7\u00e3o da fruta ou frutas inclu\u00eddas no suco, pode ser necess\u00e1rio co\u00e1-lo antes de espess\u00e1-lo.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Leite e bebidas l\u00e1cteas<\/td>\n<td align=\"left\">\n<ul>\n<li>Conseguir que o espessante fique totalmente dissolvido pode ser dif\u00edcil. Via de regra, o leite e as bebidas l\u00e1cteas que contenham leite necessitar\u00e3o um tempo mais longo de a\u00e7\u00e3o.<\/li>\n<li>O espessante costuma dissolver-se melhor se a bebida estiver quente.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Bebidas vegetais<\/td>\n<td align=\"left\">\n<ul>\n<li>A dissolu\u00e7\u00e3o do espessante nas bebidas vegetais costuma ser mais f\u00e1cil que nas bebidas l\u00e1cteas, embora tamb\u00e9m possa ser necess\u00e1rio um tempo mais longo de a\u00e7\u00e3o.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Bebidas com g\u00e1s<\/td>\n<td align=\"left\">\n<ul>\n<li>Eliminar o g\u00e1s de qualquer bebida que o contenha ajudar\u00e1 na melhor incorpora\u00e7\u00e3o do espessante. <\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td>Outras bebidas<\/td>\n<td align=\"left\">\n<ul>\n<li>No caso de bebidas como o ch\u00e1, o caf\u00e9 puro ou outras infus\u00f5es, pode ser que seja necess\u00e1ria uma quantidade maior de espessante do que o indicado para conseguir a viscosidade desejada.<\/li>\n<li>Se houver um suplemento nutricional prescrito, ser\u00e1 necess\u00e1rio adaptar sua viscosidade considerando essas recomenda\u00e7\u00f5es.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/table>\n<\/td>\n<\/tr>\n<\/table><\/div>\n<div class=\"col-md-12 descrip\">\n<p>De qualquer forma, sempre consulte a equipe que lhe ajuda nos cuidados, para que o fonoaudi\u00f3logo lhe oriente na quantidade correta ou ainda o o nutricionista lhe forne\u00e7a op\u00e7\u00f5es de espessantes caseiros.<br \/>\nSe quiser conhecer um pouco mais sobre o assunto, consulte esse link que deixamos aqui sobre um manual do usu\u00e1rio para uso de espessantes caseiros.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Tomar a medica\u00e7\u00e3o com alimentos, bebidas ou \u00e1guas gelificadas que tamb\u00e9m tenham a viscosidade indicada.<\/h3>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Manter uma boa postura. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Sentado ou quanto mais ereto melhor, sempre evitando a hiperextens\u00e3o da cabe\u00e7a, , conforme demostrado na figura abaixo.<\/p>\n<\/p><\/div>\n<div class=\"col-md-12\">\n                            <img decoding=\"async\" style=\"max-width:50%;\" src=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2026\/06\/Postura-.png\" \/>\n                        <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-2\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Levar o tempo necess\u00e1rio para comer e evitar acumular alimentos dentro da boca. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-2\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Comer lentamente e com tempo suficiente entre cada colherada.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-4\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Evitar prepara\u00e7\u00f5es ou alimentos com duas texturas diferentes. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-4\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>S\u00e3o aquelas compostas por parte l\u00edquida e s\u00f3lida: sopa com macarr\u00e3o, arroz-doce, iogurte com granola, leite com bolos ou biscoitos, e alimentos como a tangerina\/mexerica, a laranja ou as frutas muito suculentas. Ambas as texturas na boca impedem controlar a degluti\u00e7\u00e3o dos l\u00edquidos.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-5\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Evitar alimentos muito fibrosos. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-5\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Como o abacaxi, vagens, milho cozido,  alcachofras, os aspargos e as carnes fibrosas, ou aqueles que se despeda\u00e7am facilmente ao mastigar, como biscoitos, chips, grissinis de p\u00e3o torrado ou frutos secos\/oleaginosas. Evitar tamb\u00e9m as leguminosas das quais a casca se desprenda facilmente.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-6\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Evitar sorvetes, picol\u00e9s, raspadinhas e gelatinas comerciais. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-6\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Ao entrar em contato com o calor da boca e a saliva se tornam l\u00edquidos. Para esses tipos de prepara\u00e7\u00f5es pode-se utilizar \u00e1gar-\u00e1gar ou \u00e1guas gelificadas especiais e at\u00e9 mesmo os espessantes caseiros ou industrializados que fazem o espessamento \u00e0 frio.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3><a class=\"btn-orange recomanacions-tipus-cancer\" data-toggle=\"collapse\" href=\"#collapseExample-8\" role=\"button\" aria-expanded=\"false\" aria-controls=\"collapseExample\">Incluir ao longo do dia diferentes tipos de bebidas e evitar, assim, a monotonia. <i class=\"fa fa-angle-down\" aria-hidden=\"true\"><\/i><br \/>\n            <\/a><\/h3>\n<div class=\"collapse\" id=\"collapseExample-8\">\n<div class=\"card-body\">\n<div class=\"row\">\n<div class=\"col-md-12 descrip\">\n<p>Pode-se optar por espessar bebidas comuns seguindo as orienta\u00e7\u00f5es anteriores ou, ainda, em alguma ocasi\u00e3o, preparar bebidas com sabores diferentes ou n\u00e3o t\u00e3o t\u00edpicas. Para isso s\u00e3o elaboradas da maneira-padr\u00e3o, coadas para evitar fibras ou sementes e espessadas at\u00e9 conseguir a viscosidade desejada.<\/p>\n<\/p><\/div>\n<div class=\"col-md-12 descrip\">\n                          <b style=\"font-size: 1.4rem;\">Limonada rosa caseira<\/b><\/p>\n<p>                          <b>Ingredientes (para duas por\u00e7\u00f5es)<\/b><\/p>\n<ul>\n<li>100 g de morangos.<\/li>\n<li>50 g de mirtilos.<\/li>\n<li>70 g de suco de lim\u00e3o gelado (aproximadamente dois lim\u00f5es).<\/li>\n<li>Algumas folhas de hortel\u00e3 fresca.<\/li>\n<li>200 mL de \u00e1gua bem gelada.<\/li>\n<li>1 colher (sobremesa) de ado\u00e7ante (a\u00e7\u00facar, mel, melado etc.), opcional e conforme a prefer\u00eancia.<\/li>\n<\/ul>\n<p>                          <b>Preparo<\/b><\/p>\n<ul>\n<li>Acrescentar a um copo de mixer ou ao recipiente do processador de alimentos os morangos e os mirtilos (devem estar bem gelados e, portanto, ter estado algumas horas na geladeira antes de serem usados), limpos e sem folhas; o suco de lim\u00e3o; as folhas de hortel\u00e3; a \u00e1gua, e o a\u00e7\u00facar ou ado\u00e7ante escolhido. <\/li>\n<li>Processar tudo. <\/li>\n<li>Passar a mistura por um coador fino para eliminar qualquer part\u00edcula.<\/li>\n<li>Separar a bebida em dois copos.<\/li>\n<li>Acrescentar o espessante comercial para cada por\u00e7\u00e3o (de 200 mL e, separadamente, se quiser espessar as duas por\u00e7\u00f5es), seguindo as indica\u00e7\u00f5es do produto e a dosagem para conseguir a viscosidade desejada.* <\/li>\n<li>Verificar a viscosidade antes de consumir. Servir gelada.<\/li>\n<\/ul>\n<p>* Deve-se levar em considera\u00e7\u00e3o que, quando elaboramos bebidas que incluem ingredientes n\u00e3o l\u00edquidos, a viscosidade resultante pode corresponder a uma viscosidade n\u00e9ctar ou mel, portanto, a dosagem indicada no produto dever\u00e1 ser adaptada.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"col-md-12 p-10 text-center\">\n<h3 class=\"btn-orange recomanacions-tipus-cancer\" style=\"font-weight: bold;\">Procurar n\u00e3o comer sozinho.<\/h3>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Caracteriza-se por tosse ou pigarro com sensa\u00e7\u00e3o de engasgo posterior \u00e0 ingest\u00e3o de \u00e1gua ou outros l\u00edquidos. \u00c0s vezes, s\u00e3o produzidas tamb\u00e9m altera\u00e7\u00f5es na voz ap\u00f3s a degluti\u00e7\u00e3o. Recomenda-se modificar e adaptar a viscosidade\/textura dos l\u00edquidos, incluindo a \u00e1gua, para evitar que esses l\u00edquidos acabem sendo aspirados para o pulm\u00e3o e provoquem infec\u00e7\u00f5es pulmonares que&hellip; <a class=\"more-link\" href=\"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/\">Continue reading <span class=\"screen-reader-text\">Recomenda\u00e7\u00f5es diet\u00e9ticas para a dificuldade para deglutir l\u00edquidos em c\u00e2ncer de pulm\u00e3o<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":6695,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pulmon-a-liquidos.php","meta":{"footnotes":""},"class_list":["post-6698","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de pulm\u00e3o que apresentam dificuldade para deglutir l\u00edquidos - Oncoalicia<\/title>\n<meta name=\"description\" content=\"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de pulm\u00e3o que est\u00e3o com dificuldade para deglutir l\u00edquidos devido ao tratamento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de pulm\u00e3o que apresentam dificuldade para deglutir l\u00edquidos - Oncoalicia\" \/>\n<meta property=\"og:description\" content=\"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de pulm\u00e3o que est\u00e3o com dificuldade para deglutir l\u00edquidos devido ao tratamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Oncoalicia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-27T09:49:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oncoalicia.com\/wp-content\/uploads\/2026\/06\/Postura-.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/\",\"name\":\"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de pulm\u00e3o que apresentam dificuldade para deglutir l\u00edquidos - Oncoalicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Postura-.png\",\"datePublished\":\"2022-05-14T06:45:57+00:00\",\"dateModified\":\"2026-06-27T09:49:09+00:00\",\"description\":\"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de pulm\u00e3o que est\u00e3o com dificuldade para deglutir l\u00edquidos devido ao tratamento.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Postura-.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Postura-.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/dificuldade-para-deglutir-liquidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipos de c\u00e2ncer\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recomenda\u00e7\u00f5es alimentares durante o tratamento do c\u00e2ncer de pulm\u00e3o\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recomenda\u00e7\u00f5es diet\u00e9ticas para a disfagia em c\u00e2ncer de pulm\u00e3o\",\"item\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/tipos-de-cancer\\\/pulmao\\\/dificuldade-ao-deglutir\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Recomenda\u00e7\u00f5es diet\u00e9ticas para a dificuldade para deglutir l\u00edquidos em c\u00e2ncer de pulm\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/\",\"name\":\"Oncoal\u00edcia\",\"description\":\"Comer durante el Tratamiento del C\u00e1ncer\",\"publisher\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#organization\"},\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#organization\",\"name\":\"Oncoal\u00edcia\",\"alternateName\":\"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"contentUrl\":\"https:\\\/\\\/oncoalicia.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_rrss.png\",\"width\":300,\"height\":300,\"caption\":\"Oncoal\u00edcia\"},\"image\":{\"@id\":\"https:\\\/\\\/oncoalicia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de pulm\u00e3o que apresentam dificuldade para deglutir l\u00edquidos - Oncoalicia","description":"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de pulm\u00e3o que est\u00e3o com dificuldade para deglutir l\u00edquidos devido ao tratamento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/","og_locale":"pt_BR","og_type":"article","og_title":"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de pulm\u00e3o que apresentam dificuldade para deglutir l\u00edquidos - Oncoalicia","og_description":"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de pulm\u00e3o que est\u00e3o com dificuldade para deglutir l\u00edquidos devido ao tratamento.","og_url":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/","og_site_name":"Oncoalicia","article_modified_time":"2026-06-27T09:49:09+00:00","og_image":[{"url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2026\/06\/Postura-.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/","url":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/","name":"Nutri\u00e7\u00e3o para pacientes com c\u00e2ncer de pulm\u00e3o que apresentam dificuldade para deglutir l\u00edquidos - Oncoalicia","isPartOf":{"@id":"https:\/\/oncoalicia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/#primaryimage"},"image":{"@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/#primaryimage"},"thumbnailUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2026\/06\/Postura-.png","datePublished":"2022-05-14T06:45:57+00:00","dateModified":"2026-06-27T09:49:09+00:00","description":"Encontre recomenda\u00e7\u00f5es alimentares para pessoas com c\u00e2ncer de pulm\u00e3o que est\u00e3o com dificuldade para deglutir l\u00edquidos devido ao tratamento.","breadcrumb":{"@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/#primaryimage","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2026\/06\/Postura-.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2026\/06\/Postura-.png"},{"@type":"BreadcrumbList","@id":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/dificuldade-para-deglutir-liquidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oncoalicia.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Tipos de c\u00e2ncer","item":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/"},{"@type":"ListItem","position":3,"name":"Recomenda\u00e7\u00f5es alimentares durante o tratamento do c\u00e2ncer de pulm\u00e3o","item":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/"},{"@type":"ListItem","position":4,"name":"Recomenda\u00e7\u00f5es diet\u00e9ticas para a disfagia em c\u00e2ncer de pulm\u00e3o","item":"https:\/\/oncoalicia.com\/pt-br\/tipos-de-cancer\/pulmao\/dificuldade-ao-deglutir\/"},{"@type":"ListItem","position":5,"name":"Recomenda\u00e7\u00f5es diet\u00e9ticas para a dificuldade para deglutir l\u00edquidos em c\u00e2ncer de pulm\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/oncoalicia.com\/pt-br\/#website","url":"https:\/\/oncoalicia.com\/pt-br\/","name":"Oncoal\u00edcia","description":"Comer durante el Tratamiento del C\u00e1ncer","publisher":{"@id":"https:\/\/oncoalicia.com\/pt-br\/#organization"},"alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oncoalicia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oncoalicia.com\/pt-br\/#organization","name":"Oncoal\u00edcia","alternateName":"Oncoal\u00edcia | Comer durante el Tratamiento del C\u00e1ncer","url":"https:\/\/oncoalicia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oncoalicia.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","contentUrl":"https:\/\/oncoalicia.com\/wp-content\/uploads\/2022\/11\/logo_rrss.png","width":300,"height":300,"caption":"Oncoal\u00edcia"},"image":{"@id":"https:\/\/oncoalicia.com\/pt-br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages\/6698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/comments?post=6698"}],"version-history":[{"count":7,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages\/6698\/revisions"}],"predecessor-version":[{"id":11409,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages\/6698\/revisions\/11409"}],"up":[{"embeddable":true,"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/pages\/6695"}],"wp:attachment":[{"href":"https:\/\/oncoalicia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=6698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}